{"id":222,"count":23,"description":"","link":"https:\/\/hamirent.com\/blog\/category\/travel-guide\/","name":"\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u0633\u0641\u0631","slug":"travel-guide","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/hamirent.com\/blog\/wp-json\/wp\/v2\/categories\/222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hamirent.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/hamirent.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/hamirent.com\/blog\/wp-json\/wp\/v2\/posts?categories=222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}