{"id":221,"count":19,"description":"","link":"https:\/\/hamirent.com\/blog\/category\/car-rental-guide\/","name":"\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u0627\u062c\u0627\u0631\u0647 \u062e\u0648\u062f\u0631\u0648","slug":"car-rental-guide","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/hamirent.com\/blog\/wp-json\/wp\/v2\/categories\/221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hamirent.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/hamirent.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/hamirent.com\/blog\/wp-json\/wp\/v2\/posts?categories=221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}